{"id":8769,"date":"2026-02-02T15:30:40","date_gmt":"2026-02-02T14:30:40","guid":{"rendered":"https:\/\/www.sipromad.com\/?post_type=project&#038;p=8769"},"modified":"2026-02-02T15:30:44","modified_gmt":"2026-02-02T14:30:44","slug":"manager-juridique","status":"publish","type":"project","link":"https:\/\/www.sipromad.com\/en\/project\/manager-juridique\/","title":{"rendered":"MANAGER JURIDIQUE"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;rgba(124,218,36,0)&#8221; width=&#8221;85%&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;6%||6%||true|false&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;35px||30px||false|false&#8221; locked=&#8221;off&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text admin_label=&#8221;Responsable Technique&#8221; _builder_version=&#8221;4.20.0&#8243; _dynamic_attributes=&#8221;content&#8221; _module_preset=&#8221;default&#8221; header_font=&#8221;Futura Std Condensed Oblique|700||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;70px&#8221; header_font_size_tablet=&#8221;60px&#8221; header_font_size_phone=&#8221;40px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF90aXRsZSIsInNldHRpbmdzIjp7ImJlZm9yZSI6IjxoMT4iLCJhZnRlciI6IjwvaDE+In19@[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; width=&#8221;85%&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;5%|15%|5%|15%|true|true&#8221; custom_padding_tablet=&#8221;35px|10%|35px|10%|true|true&#8221; custom_padding_phone=&#8221;&#8221; locked=&#8221;off&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text admin_label=&#8221;Profil&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Futura Std Condensed Oblique|700||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;70px&#8221; header_2_font=&#8221;Futura Std Condensed Oblique|700||on|||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#000000&#8243; header_2_font_size=&#8221;40px&#8221; custom_margin=&#8221;||30px||false|false&#8221; custom_margin_tablet=&#8221;&#8221; custom_margin_phone=&#8221;||5px||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;30px&#8221; header_2_font_size_phone=&#8221;22px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<h2>R\u00e9sum\u00e9<\/h2>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Formation dipl\u00f4mante en construction&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Arial|700|||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;1.5em&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_margin_tablet=&#8221;||30px||false|false&#8221; custom_margin_phone=&#8221;||15px||false|false&#8221; custom_margin_last_edited=&#8221;on|desktop&#8221; hover_enabled=&#8221;0&#8243; text_font_size_tablet=&#8221;16px&#8221; text_font_size_phone=&#8221;14px&#8221; text_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p>Il incombe au Manager juridique de:<\/p>\n<ul>\n<li>Conseiller l\u00e9galement<\/li>\n<li>\u00c9mettre des avis objectifs et constructifs<\/li>\n<li>Pr\u00e9coniser des solutions<\/li>\n<li>Participer au d\u00e9veloppement du Groupe<\/li>\n<li>Promouvoir les principes \u00e9thiques des affaires<\/li>\n<li>Rapporter directement au Directeur juridique spontan\u00e9ment ou p\u00e9riodiquement<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#000000&#8243; width=&#8221;85%&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;5%|15%|5%|15%|true|true&#8221; custom_padding_tablet=&#8221;35px|10%|35px|10%|true|true&#8221; custom_padding_phone=&#8221;&#8221; locked=&#8221;off&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text admin_label=&#8221;Comp\u00e9tences&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Futura Std Condensed Oblique|700||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;70px&#8221; header_2_font=&#8221;Futura Std Condensed Oblique|700||on|||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;40px&#8221; custom_margin=&#8221;||30px||false|false&#8221; custom_margin_tablet=&#8221;&#8221; custom_margin_phone=&#8221;||5px||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;30px&#8221; header_2_font_size_phone=&#8221;22px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<h2>Qualifications et comp\u00e9tences<\/h2>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Excellentes connaissances techniques &#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Arial|700|||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;1.5em&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||50px||false|false&#8221; custom_margin_tablet=&#8221;||30px||false|false&#8221; custom_margin_phone=&#8221;||15px||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; hover_enabled=&#8221;0&#8243; text_font_size_tablet=&#8221;16px&#8221; text_font_size_phone=&#8221;14px&#8221; text_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p>Dipl\u00f4me de l&#8217;enseignement sup\u00e9rieur BAC+5 en sciences juridiques, assorti d\u2019une exp\u00e9rience professionnelle de 5 ann\u00e9es minimum en cabinet juridique et\/ou en entreprises.<\/p>\n<p>Langues\u00a0: fran\u00e7ais courant, ma\u00eetrise de l\u2019anglais professionnel.<\/p>\n<p>Principales qualit\u00e9s requises\u00a0:<\/p>\n<ul>\n<li>Rigueur<\/li>\n<li>Discr\u00e9tion et sens de la confidentialit\u00e9<\/li>\n<li>Sens de la communication.<\/li>\n<li>Dynamisme.<\/li>\n<li>Capacit\u00e9 d&#8217;adaptation.<\/li>\n<li>Force de persuasion.<\/li>\n<li>Gestion du stress.<\/li>\n<li>Travail en \u00e9quipe.<\/li>\n<li>Capacit\u00e9 \u00e0 f\u00e9d\u00e9rer.<\/li>\n<li>Capacit\u00e9 d&#8217;analyse.<\/li>\n<li>Proactivit\u00e9 notamment sur le suivi de l\u2019\u00e9volution des dossiers aupr\u00e8s du Directeur<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; width=&#8221;85%&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;5%|15%|5%|15%|true|true&#8221; custom_padding_tablet=&#8221;35px|10%|35px|10%|true|true&#8221; custom_padding_phone=&#8221;&#8221; locked=&#8221;off&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text admin_label=&#8221;Missions&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Futura Std Condensed Oblique|700||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;70px&#8221; header_2_font=&#8221;Futura Std Condensed Oblique|700||on|||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#000000&#8243; header_2_font_size=&#8221;40px&#8221; custom_margin=&#8221;||30px||false|false&#8221; custom_margin_tablet=&#8221;&#8221; custom_margin_phone=&#8221;||5px||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;30px&#8221; header_2_font_size_phone=&#8221;22px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<h2>Responsabilit\u00e9s<\/h2>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Au sein du p\u00f4le immobilier&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Arial|700|||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;1.5em&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_margin_tablet=&#8221;||30px||false|false&#8221; custom_margin_phone=&#8221;||15px||false|false&#8221; custom_margin_last_edited=&#8221;on|desktop&#8221; hover_enabled=&#8221;0&#8243; text_font_size_tablet=&#8221;16px&#8221; text_font_size_phone=&#8221;14px&#8221; text_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p><strong>En tant que chef d\u2019\u00e9quipe<\/strong>\u00a0:<\/p>\n<ul>\n<li><strong>Support <\/strong>du Directeur juridique dans la gestion des t\u00e2ches du D\u00e9partement et reporte directement au Directeur juridique<\/li>\n<li><strong>Contr\u00f4le<\/strong> et supervise les travaux confi\u00e9s aux membres de l\u2019\u00e9quipe<\/li>\n<li><strong>\u00c9tablit <\/strong>les plans d\u2019actions et assure le suivi des activit\u00e9s du D\u00e9partement (consultations, contrats, dossiers confi\u00e9s aux auxiliaires de justice, contentieux, archivages, correspondances)<\/li>\n<li><strong>Revoit <\/strong>les diff\u00e9rents avis et documents r\u00e9dig\u00e9s par le D\u00e9partement<\/li>\n<li><strong>Aide \u00e0 la prise de d\u00e9cision<\/strong> en pr\u00e9sentant les contraintes et obligations l\u00e9gales<\/li>\n<li>\u00ab\u00a0<strong>Back-up<\/strong>\u00bb (rempla\u00e7ant) du Directeur juridique en cas d\u2019absence<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>Sur le plan technique\/juridique\u00a0:<\/strong><\/p>\n<ul>\n<li><strong>Secr\u00e9taire <\/strong>et signataire de tous les proc\u00e8s-verbaux des r\u00e9unions des organes sociaux (Conseil d\u2019Administration et Assembl\u00e9es G\u00e9n\u00e9rales d\u2019actionnaires\/associ\u00e9s) de toutes les soci\u00e9t\u00e9s du Groupe\u00a0;<\/li>\n<li><strong>Etablit<\/strong> et propose les affectations de r\u00e9sultats annuels<\/li>\n<li><strong>Garant de la conformit\u00e9 <\/strong>l\u00e9gale et des <strong>int\u00e9r\u00eats de la Soci\u00e9t\u00e9 <\/strong>dans toutes les d\u00e9cisions\/r\u00e9solutions prises par les organes sociaux<\/li>\n<li><strong>Conseille <\/strong>chaque membre de l\u2019\u00e9quipe dans toutes consultations soumises au d\u00e9partement<\/li>\n<li><strong>R\u00e9dige <\/strong>tous actes juridiques et consultations \u00e0 la demande du Directeur juridique<\/li>\n<li><strong>Veille <\/strong>aux \u00e9volutions de la l\u00e9gislation notamment en participant activement aux rencontres et ateliers de discussions ou d\u2019\u00e9laboration des nouvelles lois, de son propre chef ou en tant que repr\u00e9sentant du d\u00e9partement juridique<\/li>\n<li><strong>Traite <\/strong>les dossiers sensibles confi\u00e9s par le Directeur juridique, ainsi que les dossiers de financement locaux ou \u00e0 l\u2019international<\/li>\n<li><strong>Contr\u00f4le <\/strong>de premier niveau de tous les travaux et rapports de travail de l\u2019\u00e9quipe juridique<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; width=&#8221;85%&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;4%|15%|4%|15%|true|true&#8221; custom_padding_tablet=&#8221;35px|10%|35px|10%|true|true&#8221; custom_padding_phone=&#8221;&#8221; locked=&#8221;off&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_button button_url=&#8221;#&#8221; url_new_window=&#8221;on&#8221; button_text=&#8221;Soumettre votre candidature&#8221; button_alignment=&#8221;center&#8221; disabled_on=&#8221;on|off|off&#8221; admin_label=&#8221;Soumettre votre candidature&#8221; module_class=&#8221;buttonHover postulePoste&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;20px&#8221; button_text_color=&#8221;#FFFFFF&#8221; button_bg_color=&#8221;#e15f3f&#8221; button_border_width=&#8221;1px&#8221; button_border_color=&#8221;#e15f3f&#8221; button_border_radius=&#8221;0px&#8221; button_font=&#8221;Futura Std Condesed|||on|||||&#8221; button_use_icon=&#8221;off&#8221; overflow-x=&#8221;hidden&#8221; overflow-y=&#8221;hidden&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;1.5em|3em|1.5em|3em|true|true&#8221; button_text_size_tablet=&#8221;18px&#8221; button_text_size_phone=&#8221;16px&#8221; button_text_size_last_edited=&#8221;on|phone&#8221; button_text_color_last_edited=&#8221;off|desktop&#8221; custom_css_main_element=&#8221;line-height: 0 !important;&#8221; global_colors_info=&#8221;{}&#8221; button_bg_color__hover_enabled=&#8221;on|desktop&#8221; button_bg_color__hover=&#8221;#FFFFFF&#8221; button_bg_enable_color__hover=&#8221;on&#8221; button_text_color__hover_enabled=&#8221;on|hover&#8221; button_text_color__hover=&#8221;#e15f3f&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R\u00e9sum\u00e9Il incombe au Manager juridique de: Conseiller l\u00e9galement \u00c9mettre des avis objectifs et constructifs Pr\u00e9coniser des solutions Participer au d\u00e9veloppement du Groupe Promouvoir les principes \u00e9thiques des affaires Rapporter directement au Directeur juridique spontan\u00e9ment ou p\u00e9riodiquement Qualifications et comp\u00e9tencesDipl\u00f4me de l&#8217;enseignement sup\u00e9rieur BAC+5 en sciences juridiques, assorti d\u2019une exp\u00e9rience professionnelle de 5 ann\u00e9es minimum en [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"project_category":[65,62,60,84],"project_tag":[],"class_list":["post-8769","project","type-project","status-publish","hentry","project_category-antananarivo-en","project_category-cdi-en","project_category-contract","project_category-sipromad-group"],"_links":{"self":[{"href":"https:\/\/www.sipromad.com\/en\/wp-json\/wp\/v2\/project\/8769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sipromad.com\/en\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/www.sipromad.com\/en\/wp-json\/wp\/v2\/types\/project"}],"author":[{"embeddable":true,"href":"https:\/\/www.sipromad.com\/en\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sipromad.com\/en\/wp-json\/wp\/v2\/comments?post=8769"}],"version-history":[{"count":2,"href":"https:\/\/www.sipromad.com\/en\/wp-json\/wp\/v2\/project\/8769\/revisions"}],"predecessor-version":[{"id":8772,"href":"https:\/\/www.sipromad.com\/en\/wp-json\/wp\/v2\/project\/8769\/revisions\/8772"}],"wp:attachment":[{"href":"https:\/\/www.sipromad.com\/en\/wp-json\/wp\/v2\/media?parent=8769"}],"wp:term":[{"taxonomy":"project_category","embeddable":true,"href":"https:\/\/www.sipromad.com\/en\/wp-json\/wp\/v2\/project_category?post=8769"},{"taxonomy":"project_tag","embeddable":true,"href":"https:\/\/www.sipromad.com\/en\/wp-json\/wp\/v2\/project_tag?post=8769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}