{"id":8726,"date":"2026-02-02T14:42:55","date_gmt":"2026-02-02T13:42:55","guid":{"rendered":"https:\/\/www.sipromad.com\/?post_type=project&#038;p=8726"},"modified":"2026-02-02T14:42:59","modified_gmt":"2026-02-02T13:42:59","slug":"responsable-circuit-traditionnel","status":"publish","type":"project","link":"https:\/\/www.sipromad.com\/en\/project\/responsable-circuit-traditionnel\/","title":{"rendered":"RESPONSABLE CIRCUIT TRADITIONNEL"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;rgba(124,218,36,0)&#8221; width=&#8221;85%&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;6%||6%||true|false&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;35px||30px||false|false&#8221; locked=&#8221;off&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text admin_label=&#8221;Responsable Technique&#8221; _builder_version=&#8221;4.20.0&#8243; _dynamic_attributes=&#8221;content&#8221; _module_preset=&#8221;default&#8221; header_font=&#8221;Futura Std Condensed Oblique|700||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;70px&#8221; header_font_size_tablet=&#8221;60px&#8221; header_font_size_phone=&#8221;40px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF90aXRsZSIsInNldHRpbmdzIjp7ImJlZm9yZSI6IjxoMT4iLCJhZnRlciI6IjwvaDE+In19@[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; width=&#8221;85%&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;5%|15%|5%|15%|true|true&#8221; custom_padding_tablet=&#8221;35px|10%|35px|10%|true|true&#8221; custom_padding_phone=&#8221;&#8221; locked=&#8221;off&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text admin_label=&#8221;Profil&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Futura Std Condensed Oblique|700||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;70px&#8221; header_2_font=&#8221;Futura Std Condensed Oblique|700||on|||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#000000&#8243; header_2_font_size=&#8221;40px&#8221; custom_margin=&#8221;||30px||false|false&#8221; custom_margin_tablet=&#8221;&#8221; custom_margin_phone=&#8221;||5px||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; hover_enabled=&#8221;0&#8243; header_2_font_size_tablet=&#8221;30px&#8221; header_2_font_size_phone=&#8221;22px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h2>R\u00e9sum\u00e9<\/h2>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Formation dipl\u00f4mante en construction&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Arial|700|||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;1.5em&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_margin_tablet=&#8221;||30px||false|false&#8221; custom_margin_phone=&#8221;||15px||false|false&#8221; custom_margin_last_edited=&#8221;on|desktop&#8221; hover_enabled=&#8221;0&#8243; text_font_size_tablet=&#8221;16px&#8221; text_font_size_phone=&#8221;14px&#8221; text_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p>Le Responsable Circuit traditionnel a pour mission de croitre, et de rendre disponible les produits \u00e0 travers l\u2019univers clients existant susceptible de r\u00e9f\u00e9rencer l\u2019\u00e9tendue des produits de Sipromad-P\u00f4le Distribution, grossistes, demi-gros, \u00e9piceries, autres.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#000000&#8243; width=&#8221;85%&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;5%|15%|5%|15%|true|true&#8221; custom_padding_tablet=&#8221;35px|10%|35px|10%|true|true&#8221; custom_padding_phone=&#8221;&#8221; locked=&#8221;off&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text admin_label=&#8221;Comp\u00e9tences&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Futura Std Condensed Oblique|700||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;70px&#8221; header_2_font=&#8221;Futura Std Condensed Oblique|700||on|||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;40px&#8221; custom_margin=&#8221;||30px||false|false&#8221; custom_margin_tablet=&#8221;&#8221; custom_margin_phone=&#8221;||5px||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;30px&#8221; header_2_font_size_phone=&#8221;22px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<h2>Qualifications et comp\u00e9tences<\/h2>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Excellentes connaissances techniques &#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Arial|700|||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;1.5em&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||50px||false|false&#8221; custom_margin_tablet=&#8221;||30px||false|false&#8221; custom_margin_phone=&#8221;||15px||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; hover_enabled=&#8221;0&#8243; text_font_size_tablet=&#8221;16px&#8221; text_font_size_phone=&#8221;14px&#8221; text_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p><strong>Comp\u00e9tences requises :<\/strong><\/p>\n<ul>\n<li>Excellentes comp\u00e9tences en n\u00e9gociation et en gestion de la relation client.<\/li>\n<li>Bonne connaissance du secteur de la distribution et de ses acteurs,<\/li>\n<li>Maitrise du circuit traditionnel<\/li>\n<li>Ma\u00eetrise des techniques de vente et de marketing.<\/li>\n<li>Capacit\u00e9 d\u2019analyse et de synth\u00e8se pour optimiser les performances commerciales.<\/li>\n<li>Aisance avec les outils CRM et les logiciels de reporting.<\/li>\n<\/ul>\n<p><strong>Formation et exp\u00e9rience :<\/strong><\/p>\n<ul>\n<li>Bac +3 \u00e0 Bac +5 en commerce, gestion ou marketing.<\/li>\n<li>Exp\u00e9rience significative (3 \u00e0 5 ans minimum) dans un poste similaire, id\u00e9alement dans le secteur de la distribution ou des biens de grande consommation.<\/li>\n<\/ul>\n<p><strong>Qualit\u00e9s personnelles :<\/strong><\/p>\n<ul>\n<li>Forte capacit\u00e9 d\u2019adaptation et esprit d\u2019initiative.<\/li>\n<li>Sens du r\u00e9sultat et orientation client.<\/li>\n<li>Aptitude \u00e0 travailler en \u00e9quipe et en mode projet.<\/li>\n<li>Mobilit\u00e9 et disponibilit\u00e9 pour des d\u00e9placements fr\u00e9quents.<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; width=&#8221;85%&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;5%|15%|5%|15%|true|true&#8221; custom_padding_tablet=&#8221;35px|10%|35px|10%|true|true&#8221; custom_padding_phone=&#8221;&#8221; locked=&#8221;off&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text admin_label=&#8221;Missions&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Futura Std Condensed Oblique|700||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;70px&#8221; header_2_font=&#8221;Futura Std Condensed Oblique|700||on|||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#000000&#8243; header_2_font_size=&#8221;40px&#8221; custom_margin=&#8221;||30px||false|false&#8221; custom_margin_tablet=&#8221;&#8221; custom_margin_phone=&#8221;||5px||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;30px&#8221; header_2_font_size_phone=&#8221;22px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<h2>Responsabilit\u00e9s<\/h2>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Au sein du p\u00f4le immobilier&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Arial|700|||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;1.5em&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_margin_tablet=&#8221;||30px||false|false&#8221; custom_margin_phone=&#8221;||15px||false|false&#8221; custom_margin_last_edited=&#8221;on|desktop&#8221; hover_enabled=&#8221;0&#8243; text_font_size_tablet=&#8221;16px&#8221; text_font_size_phone=&#8221;14px&#8221; text_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p><strong>D\u00e9veloppement commercial :<\/strong><\/p>\n<ul>\n<li>D\u00e9finir et mettre en \u0153uvre la strat\u00e9gie commerciale pour son p\u00e9rim\u00e8tre (SICD).<\/li>\n<li>Prospecter de nouveaux clients et d\u00e9velopper les partenariats existants.<\/li>\n<li>Assurer une veille concurrentielle et identifier les opportunit\u00e9s de croissance.<\/li>\n<li>Accompagner sur terrain<\/li>\n<\/ul>\n<p><strong>Gestion du portefeuille clients :<\/strong><\/p>\n<ul>\n<li>N\u00e9gocier les accords commerciaux avec les distributeurs.<\/li>\n<li>Suivre et analyser les performances des ventes.<\/li>\n<li>Garantir la satisfaction et la fid\u00e9lisation des clients.<\/li>\n<\/ul>\n<p><strong>Coordination et reporting :<\/strong><\/p>\n<ul>\n<li>Collaborer avec les \u00e9quipes marketing et logistique pour assurer un bon d\u00e9ploiement des offres.<\/li>\n<li>Rendre compte de son activit\u00e9 \u00e0 la direction commerciale (reportings, KPIs, analyses de march\u00e9).<\/li>\n<li>Participer \u00e0 la d\u00e9finition des pr\u00e9visions de ventes et des objectifs.<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; width=&#8221;85%&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;4%|15%|4%|15%|true|true&#8221; custom_padding_tablet=&#8221;35px|10%|35px|10%|true|true&#8221; custom_padding_phone=&#8221;&#8221; locked=&#8221;off&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_button button_url=&#8221;#&#8221; url_new_window=&#8221;on&#8221; button_text=&#8221;Soumettre votre candidature&#8221; button_alignment=&#8221;center&#8221; disabled_on=&#8221;on|off|off&#8221; admin_label=&#8221;Soumettre votre candidature&#8221; module_class=&#8221;buttonHover postulePoste&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;20px&#8221; button_text_color=&#8221;#FFFFFF&#8221; button_bg_color=&#8221;#e15f3f&#8221; button_border_width=&#8221;1px&#8221; button_border_color=&#8221;#e15f3f&#8221; button_border_radius=&#8221;0px&#8221; button_font=&#8221;Futura Std Condesed|||on|||||&#8221; button_use_icon=&#8221;off&#8221; overflow-x=&#8221;hidden&#8221; overflow-y=&#8221;hidden&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;1.5em|3em|1.5em|3em|true|true&#8221; button_text_size_tablet=&#8221;18px&#8221; button_text_size_phone=&#8221;16px&#8221; button_text_size_last_edited=&#8221;on|phone&#8221; button_text_color_last_edited=&#8221;off|desktop&#8221; custom_css_main_element=&#8221;line-height: 0 !important;&#8221; global_colors_info=&#8221;{}&#8221; button_bg_color__hover_enabled=&#8221;on|desktop&#8221; button_bg_color__hover=&#8221;#FFFFFF&#8221; button_bg_enable_color__hover=&#8221;on&#8221; button_text_color__hover_enabled=&#8221;on|hover&#8221; button_text_color__hover=&#8221;#e15f3f&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R\u00e9sum\u00e9Le Responsable Circuit traditionnel a pour mission de croitre, et de rendre disponible les produits \u00e0 travers l\u2019univers clients existant susceptible de r\u00e9f\u00e9rencer l\u2019\u00e9tendue des produits de Sipromad-P\u00f4le Distribution, grossistes, demi-gros, \u00e9piceries, autres.Qualifications et comp\u00e9tencesComp\u00e9tences requises : Excellentes comp\u00e9tences en n\u00e9gociation et en gestion de la relation client. Bonne connaissance du secteur de la distribution [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"project_category":[65,62,60,84],"project_tag":[],"class_list":["post-8726","project","type-project","status-publish","hentry","project_category-antananarivo-en","project_category-cdi-en","project_category-contract","project_category-sipromad-group"],"_links":{"self":[{"href":"https:\/\/www.sipromad.com\/en\/wp-json\/wp\/v2\/project\/8726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sipromad.com\/en\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/www.sipromad.com\/en\/wp-json\/wp\/v2\/types\/project"}],"author":[{"embeddable":true,"href":"https:\/\/www.sipromad.com\/en\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sipromad.com\/en\/wp-json\/wp\/v2\/comments?post=8726"}],"version-history":[{"count":2,"href":"https:\/\/www.sipromad.com\/en\/wp-json\/wp\/v2\/project\/8726\/revisions"}],"predecessor-version":[{"id":8728,"href":"https:\/\/www.sipromad.com\/en\/wp-json\/wp\/v2\/project\/8726\/revisions\/8728"}],"wp:attachment":[{"href":"https:\/\/www.sipromad.com\/en\/wp-json\/wp\/v2\/media?parent=8726"}],"wp:term":[{"taxonomy":"project_category","embeddable":true,"href":"https:\/\/www.sipromad.com\/en\/wp-json\/wp\/v2\/project_category?post=8726"},{"taxonomy":"project_tag","embeddable":true,"href":"https:\/\/www.sipromad.com\/en\/wp-json\/wp\/v2\/project_tag?post=8726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}