{"id":8153,"date":"2025-05-07T14:24:21","date_gmt":"2025-05-07T12:24:21","guid":{"rendered":"https:\/\/www.sipromad.com\/?post_type=project&#038;p=8153"},"modified":"2025-05-07T14:24:28","modified_gmt":"2025-05-07T12:24:28","slug":"responsable-des-operations","status":"publish","type":"project","link":"https:\/\/www.sipromad.com\/en\/project\/responsable-des-operations\/","title":{"rendered":"RESPONSABLE DES OPERATIONS"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;rgba(124,218,36,0)&#8221; width=&#8221;85%&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;6%||6%||true|false&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;35px||30px||false|false&#8221; locked=&#8221;off&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text admin_label=&#8221;Responsable Technique&#8221; _builder_version=&#8221;4.20.0&#8243; _dynamic_attributes=&#8221;content&#8221; _module_preset=&#8221;default&#8221; header_font=&#8221;Futura Std Condensed Oblique|700||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;70px&#8221; header_font_size_tablet=&#8221;60px&#8221; header_font_size_phone=&#8221;40px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF90aXRsZSIsInNldHRpbmdzIjp7ImJlZm9yZSI6IjxoMT4iLCJhZnRlciI6IjwvaDE+In19@[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; width=&#8221;85%&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;5%|15%|5%|15%|true|true&#8221; custom_padding_tablet=&#8221;35px|10%|35px|10%|true|true&#8221; custom_padding_phone=&#8221;&#8221; locked=&#8221;off&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text admin_label=&#8221;Profil&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Futura Std Condensed Oblique|700||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;70px&#8221; header_2_font=&#8221;Futura Std Condensed Oblique|700||on|||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#000000&#8243; header_2_font_size=&#8221;40px&#8221; custom_margin=&#8221;||30px||false|false&#8221; custom_margin_tablet=&#8221;&#8221; custom_margin_phone=&#8221;||5px||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; hover_enabled=&#8221;0&#8243; header_2_font_size_tablet=&#8221;30px&#8221; header_2_font_size_phone=&#8221;22px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h2>R\u00e9sum\u00e9<\/h2>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Formation dipl\u00f4mante en construction&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Arial|700|||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;1.5em&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_margin_tablet=&#8221;||30px||false|false&#8221; custom_margin_phone=&#8221;||15px||false|false&#8221; custom_margin_last_edited=&#8221;on|desktop&#8221; hover_enabled=&#8221;0&#8243; text_font_size_tablet=&#8221;16px&#8221; text_font_size_phone=&#8221;14px&#8221; text_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p>Le\/La Responsable des Op\u00e9rations est charg\u00e9(e) de superviser et d&#8217;optimiser l&#8217;ensemble des activit\u00e9s op\u00e9rationnelles du Groupe. Il\/Elle assure l&#8217;efficacit\u00e9, la qualit\u00e9 et la rentabilit\u00e9 des processus, en veillant \u00e0 l&#8217;atteinte des objectifs strat\u00e9giques de l&#8217;organisation.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#000000&#8243; width=&#8221;85%&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;5%|15%|5%|15%|true|true&#8221; custom_padding_tablet=&#8221;35px|10%|35px|10%|true|true&#8221; custom_padding_phone=&#8221;&#8221; locked=&#8221;off&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text admin_label=&#8221;Comp\u00e9tences&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Futura Std Condensed Oblique|700||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;70px&#8221; header_2_font=&#8221;Futura Std Condensed Oblique|700||on|||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;40px&#8221; custom_margin=&#8221;||30px||false|false&#8221; custom_margin_tablet=&#8221;&#8221; custom_margin_phone=&#8221;||5px||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; hover_enabled=&#8221;0&#8243; header_2_font_size_tablet=&#8221;30px&#8221; header_2_font_size_phone=&#8221;22px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h2>Qualifications et comp\u00e9tences<\/h2>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Excellentes connaissances techniques &#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Arial|700|||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;1.5em&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||50px||false|false&#8221; custom_margin_tablet=&#8221;||30px||false|false&#8221; custom_margin_phone=&#8221;||15px||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; hover_enabled=&#8221;0&#8243; text_font_size_tablet=&#8221;16px&#8221; text_font_size_phone=&#8221;14px&#8221; text_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<ul>\n<li><strong>Comp\u00e9tences Techniques:<\/strong>\n<ul>\n<li>Excellente connaissance des principes et des meilleures pratiques en gestion des op\u00e9rations.<\/li>\n<li>Ma\u00eetrise des outils et des syst\u00e8mes de gestion op\u00e9rationnelle (ERP, CRM, etc.).<\/li>\n<li>Connaissance des normes de qualit\u00e9 (ISO, etc.), de s\u00e9curit\u00e9 et environnementales.<\/li>\n<li>Capacit\u00e9 \u00e0 analyser des donn\u00e9es et \u00e0 utiliser des outils statistiques.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<ul>\n<li><strong>Comp\u00e9tences Manag\u00e9riales et Leadership:<\/strong>\n<ul>\n<li>Capacit\u00e9 \u00e0 planifier, organiser et d\u00e9l\u00e9guer efficacement.<\/li>\n<li>Leadership et capacit\u00e9 \u00e0 motiver et \u00e0 d\u00e9velopper une \u00e9quipe.<\/li>\n<li>Excellentes comp\u00e9tences en communication interpersonnelle et en r\u00e9solution de conflits.<\/li>\n<li>Capacit\u00e9 \u00e0 prendre des d\u00e9cisions et \u00e0 r\u00e9soudre des probl\u00e8mes de mani\u00e8re efficace.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<ul>\n<li><strong>Comp\u00e9tences Personnelles:<\/strong>\n<ul>\n<li>Esprit d&#8217;analyse et de synth\u00e8se.<\/li>\n<li>Orientation r\u00e9sultats et sens de la performance.<\/li>\n<li>Rigueur, organisation et m\u00e9thode.<\/li>\n<li>Capacit\u00e9 d&#8217;adaptation et flexibilit\u00e9.<\/li>\n<li>Proactivit\u00e9 et force de proposition.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<ul>\n<li><strong>Qualifications et Exp\u00e9rience<\/strong>\n<ul>\n<li>Dipl\u00f4me de niveau [Bac +3\/Licence] \u00e0 [Bac +5\/Master] en gestion des op\u00e9rations, logistique, ing\u00e9nierie industrielle ou domaine \u00e9quivalent.<\/li>\n<li>Exp\u00e9rience significative dans un poste similaire, avec une exp\u00e9rience av\u00e9r\u00e9e en management d&#8217;\u00e9quipe.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; width=&#8221;85%&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;5%|15%|5%|15%|true|true&#8221; custom_padding_tablet=&#8221;35px|10%|35px|10%|true|true&#8221; custom_padding_phone=&#8221;&#8221; locked=&#8221;off&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text admin_label=&#8221;Missions&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Futura Std Condensed Oblique|700||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;70px&#8221; header_2_font=&#8221;Futura Std Condensed Oblique|700||on|||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#000000&#8243; header_2_font_size=&#8221;40px&#8221; custom_margin=&#8221;||30px||false|false&#8221; custom_margin_tablet=&#8221;&#8221; custom_margin_phone=&#8221;||5px||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; hover_enabled=&#8221;0&#8243; header_2_font_size_tablet=&#8221;30px&#8221; header_2_font_size_phone=&#8221;22px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h2>Responsabilit\u00e9s<\/h2>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Au sein du p\u00f4le immobilier&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Arial|700|||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;1.5em&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_margin_tablet=&#8221;||30px||false|false&#8221; custom_margin_phone=&#8221;||15px||false|false&#8221; custom_margin_last_edited=&#8221;on|desktop&#8221; hover_enabled=&#8221;0&#8243; text_font_size_tablet=&#8221;16px&#8221; text_font_size_phone=&#8221;14px&#8221; text_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p><strong>Planification et Organisation des Op\u00e9rations:<\/strong><\/p>\n<ul>\n<li>D\u00e9finir et mettre en \u0153uvre les strat\u00e9gies et les politiques op\u00e9rationnelles.<\/li>\n<li>\u00c9laborer les plans de production, de logistique, de maintenance ou autres, en fonction du secteur d&#8217;activit\u00e9.<\/li>\n<li>Organiser et coordonner les ressources (humaines, mat\u00e9rielles, financi\u00e8res) n\u00e9cessaires au bon d\u00e9roulement des op\u00e9rations.<\/li>\n<li>\u00c9tablir les objectifs de performance op\u00e9rationnelle et les indicateurs cl\u00e9s de performance (KPIs).<\/li>\n<\/ul>\n<p><strong>Gestion et Optimisation des Processus:<\/strong><\/p>\n<ul>\n<li>Analyser les processus existants, identifier les points d&#8217;am\u00e9lioration et proposer des solutions pour optimiser l&#8217;efficacit\u00e9, r\u00e9duire les co\u00fbts et am\u00e9liorer la qualit\u00e9.<\/li>\n<li>Mettre en place et suivre les proc\u00e9dures op\u00e9rationnelles standardis\u00e9es.<\/li>\n<li>Superviser l&#8217;application des normes de qualit\u00e9, de s\u00e9curit\u00e9 et environnementales.<\/li>\n<li>Participer \u00e0 l&#8217;impl\u00e9mentation de nouvelles technologies et de nouveaux syst\u00e8mes d&#8217;information pour am\u00e9liorer les op\u00e9rations.<\/li>\n<\/ul>\n<p><strong>Management d&#8217;\u00c9quipe:<\/strong><\/p>\n<ul>\n<li>Recruter, former, encadrer et \u00e9valuer les \u00e9quipes op\u00e9rationnelles.<\/li>\n<li>D\u00e9finir les r\u00f4les et responsabilit\u00e9s de chaque membre de l&#8217;\u00e9quipe.<\/li>\n<li>Favoriser un environnement de travail collaboratif et motivant.<\/li>\n<li>G\u00e9rer les conflits et assurer une communication efficace au sein de l&#8217;\u00e9quipe.<\/li>\n<\/ul>\n<p><strong>Suivi et Analyse de la Performance:<\/strong><\/p>\n<ul>\n<li>Collecter et analyser les donn\u00e9es de performance op\u00e9rationnelle.<\/li>\n<li>\u00c9tablir des rapports r\u00e9guliers sur les r\u00e9sultats obtenus et les \u00e9carts par rapport aux objectifs.<\/li>\n<li>Identifier les tendances et les probl\u00e8mes, et proposer des actions correctives.<\/li>\n<li>Mettre en place des tableaux de bord de suivi de la performance.<\/li>\n<\/ul>\n<p><strong>Gestion Budg\u00e9taire:<\/strong><\/p>\n<ul>\n<li>Participer \u00e0 l&#8217;\u00e9laboration du budget des op\u00e9rations.<\/li>\n<li>Suivre et contr\u00f4ler les d\u00e9penses op\u00e9rationnelles.<\/li>\n<li>Identifier les opportunit\u00e9s de r\u00e9duction des co\u00fbts.<\/li>\n<\/ul>\n<p><strong>Collaboration et Communication:<\/strong><\/p>\n<ul>\n<li>Travailler en \u00e9troite collaboration avec les autres d\u00e9partements de l&#8217;entreprise (ventes, marketing, finance, ressources humaines, etc.).<\/li>\n<li>Communiquer de mani\u00e8re claire et efficace avec les diff\u00e9rentes parties prenantes (internes et externes).<\/li>\n<li>Participer aux r\u00e9unions de direction et pr\u00e9senter les r\u00e9sultats des op\u00e9rations.<\/li>\n<\/ul>\n<p><strong>Gestion des Risques:<\/strong><\/p>\n<ul>\n<li>Identifier et \u00e9valuer les risques op\u00e9rationnels potentiels.<\/li>\n<li>Mettre en place des mesures de pr\u00e9vention et de mitigation des risques.<\/li>\n<li>G\u00e9rer les situations d&#8217;urgence et les impr\u00e9vus.<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; width=&#8221;85%&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;4%|15%|4%|15%|true|true&#8221; custom_padding_tablet=&#8221;35px|10%|35px|10%|true|true&#8221; custom_padding_phone=&#8221;&#8221; locked=&#8221;off&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_button button_url=&#8221;#&#8221; url_new_window=&#8221;on&#8221; button_text=&#8221;Soumettre votre candidature&#8221; button_alignment=&#8221;center&#8221; disabled_on=&#8221;on|off|off&#8221; admin_label=&#8221;Soumettre votre candidature&#8221; module_class=&#8221;buttonHover postulePoste&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;20px&#8221; button_text_color=&#8221;#FFFFFF&#8221; button_bg_color=&#8221;#e15f3f&#8221; button_border_width=&#8221;1px&#8221; button_border_color=&#8221;#e15f3f&#8221; button_border_radius=&#8221;0px&#8221; button_font=&#8221;Futura Std Condesed|||on|||||&#8221; button_use_icon=&#8221;off&#8221; overflow-x=&#8221;hidden&#8221; overflow-y=&#8221;hidden&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;1.5em|3em|1.5em|3em|true|true&#8221; button_text_size_tablet=&#8221;18px&#8221; button_text_size_phone=&#8221;16px&#8221; button_text_size_last_edited=&#8221;on|phone&#8221; button_text_color_last_edited=&#8221;off|desktop&#8221; custom_css_main_element=&#8221;line-height: 0 !important;&#8221; global_colors_info=&#8221;{}&#8221; button_bg_color__hover_enabled=&#8221;on|desktop&#8221; button_bg_color__hover=&#8221;#FFFFFF&#8221; button_bg_enable_color__hover=&#8221;on&#8221; button_text_color__hover_enabled=&#8221;on|hover&#8221; button_text_color__hover=&#8221;#e15f3f&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R\u00e9sum\u00e9Le\/La Responsable des Op\u00e9rations est charg\u00e9(e) de superviser et d&#8217;optimiser l&#8217;ensemble des activit\u00e9s op\u00e9rationnelles du Groupe. Il\/Elle assure l&#8217;efficacit\u00e9, la qualit\u00e9 et la rentabilit\u00e9 des processus, en veillant \u00e0 l&#8217;atteinte des objectifs strat\u00e9giques de l&#8217;organisation.Qualifications et comp\u00e9tences Comp\u00e9tences Techniques: Excellente connaissance des principes et des meilleures pratiques en gestion des op\u00e9rations. Ma\u00eetrise des outils et [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"project_category":[65,62,84],"project_tag":[],"class_list":["post-8153","project","type-project","status-publish","hentry","project_category-antananarivo-en","project_category-cdi-en","project_category-sipromad-group"],"_links":{"self":[{"href":"https:\/\/www.sipromad.com\/en\/wp-json\/wp\/v2\/project\/8153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sipromad.com\/en\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/www.sipromad.com\/en\/wp-json\/wp\/v2\/types\/project"}],"author":[{"embeddable":true,"href":"https:\/\/www.sipromad.com\/en\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sipromad.com\/en\/wp-json\/wp\/v2\/comments?post=8153"}],"version-history":[{"count":0,"href":"https:\/\/www.sipromad.com\/en\/wp-json\/wp\/v2\/project\/8153\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sipromad.com\/en\/wp-json\/wp\/v2\/media?parent=8153"}],"wp:term":[{"taxonomy":"project_category","embeddable":true,"href":"https:\/\/www.sipromad.com\/en\/wp-json\/wp\/v2\/project_category?post=8153"},{"taxonomy":"project_tag","embeddable":true,"href":"https:\/\/www.sipromad.com\/en\/wp-json\/wp\/v2\/project_tag?post=8153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}